{"id":3071,"date":"2025-07-01T13:57:05","date_gmt":"2025-07-01T13:57:05","guid":{"rendered":"https:\/\/www.museoarcheologiconapoli.it\/projects\/"},"modified":"2025-07-16T09:41:21","modified_gmt":"2025-07-16T09:41:21","slug":"projects","status":"publish","type":"page","link":"https:\/\/www.museoarcheologiconapoli.it\/en\/projects\/","title":{"rendered":"Projects"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column]<div class=\"wpex-post-cards wpex-post-cards-template_1368 wpex-relative\"><div class=\"wpex-post-cards-inner\"><div class=\"wpex-post-cards-loop wpex-post-cards-grid wpex-row wpex-clr\"><div class=\"wpex-post-cards-entry col col-1 span_1_of_2 post-5298 type-post cat-98\"><div class=\"wpex-card wpex-card-template_1368\"><a href=\"https:\/\/www.museoarcheologiconapoli.it\/en\/acqua-storia-comune-neapolis\/\" aria-label=\"Acqua storia comune Neapolis\" class=\"wpex-card-inner wpex-no-underline wpex-inherit-color\"><div class=\"vc_row wpb_row vc_row-fluid wpex-relative wpex-vc_row-col-mb-0\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><figure class=\"vcex-image vcex-module vcex-fill-column\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><img width=\"1140\" height=\"580\" src=\"https:\/\/www.museoarcheologiconapoli.it\/mann\/uploads\/2025\/07\/slide_acqua-1.jpg\" class=\"vcex-image-img wpex-align-middle\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.museoarcheologiconapoli.it\/mann\/uploads\/2025\/07\/slide_acqua-1.jpg 1140w, https:\/\/www.museoarcheologiconapoli.it\/mann\/uploads\/2025\/07\/slide_acqua-1-300x153.jpg 300w, https:\/\/www.museoarcheologiconapoli.it\/mann\/uploads\/2025\/07\/slide_acqua-1-1024x521.jpg 1024w, https:\/\/www.museoarcheologiconapoli.it\/mann\/uploads\/2025\/07\/slide_acqua-1-768x391.jpg 768w\" sizes=\"auto, (max-width: 1140px) 100vw, 1140px\" \/><\/div><\/figure><div class=\"vcex-spacing wpex-w-100 wpex-clear\" style=\"height:20px;\"><\/div><style>.vcex-heading.vcex_6a04b846510eb{font-size:18px;font-weight:700;line-height:23px;}<\/style><div class=\"vcex-heading vcex-heading-plain vcex-module wpex-heading wpex-text-2xl vcex_6a04b846510eb\"><span class=\"vcex-heading-inner wpex-inline-block\">Acqua storia comune Neapolis<\/span><\/div><\/div><\/div><\/div><\/div><\/a><\/div><\/div><div class=\"wpex-post-cards-entry col col-2 span_1_of_2 post-5307 type-post cat-98 translation_priority-53\"><div class=\"wpex-card wpex-card-template_1368\"><a href=\"https:\/\/www.museoarcheologiconapoli.it\/en\/the-restoration-of-the-mosaic-of-alexander\/\" aria-label=\"The restoration of the Mosaic of Alexander\" class=\"wpex-card-inner wpex-no-underline wpex-inherit-color\"><div class=\"vc_row wpb_row vc_row-fluid wpex-relative wpex-vc_row-col-mb-0\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><figure class=\"vcex-image vcex-module vcex-fill-column\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><img width=\"1500\" height=\"1000\" src=\"https:\/\/www.museoarcheologiconapoli.it\/mann\/uploads\/2025\/07\/restauro.png\" class=\"vcex-image-img wpex-align-middle\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.museoarcheologiconapoli.it\/mann\/uploads\/2025\/07\/restauro.png 1500w, https:\/\/www.museoarcheologiconapoli.it\/mann\/uploads\/2025\/07\/restauro-300x200.png 300w, https:\/\/www.museoarcheologiconapoli.it\/mann\/uploads\/2025\/07\/restauro-1024x683.png 1024w, https:\/\/www.museoarcheologiconapoli.it\/mann\/uploads\/2025\/07\/restauro-768x512.png 768w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/><\/div><\/figure><div class=\"vcex-spacing wpex-w-100 wpex-clear\" style=\"height:20px;\"><\/div><style>.vcex-heading.vcex_6a04b84659529{font-size:18px;font-weight:700;line-height:23px;}<\/style><div class=\"vcex-heading vcex-heading-plain vcex-module wpex-heading wpex-text-2xl vcex_6a04b84659529\"><span class=\"vcex-heading-inner wpex-inline-block\">The restoration of the Mosaic of Alexander<\/span><\/div><\/div><\/div><\/div><\/div><\/a><\/div><\/div><div class=\"wpex-post-cards-entry col col-1 span_1_of_2 post-5313 type-post cat-98 translation_priority-53\"><div class=\"wpex-card wpex-card-template_1368\"><a href=\"https:\/\/www.museoarcheologiconapoli.it\/en\/progetto-obvia\/\" aria-label=\"Progetto obvia\" class=\"wpex-card-inner wpex-no-underline wpex-inherit-color\"><div class=\"vc_row wpb_row vc_row-fluid wpex-relative wpex-vc_row-col-mb-0\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><figure class=\"vcex-image vcex-module vcex-fill-column\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><img width=\"1500\" height=\"1000\" src=\"https:\/\/www.museoarcheologiconapoli.it\/mann\/uploads\/2025\/07\/obvia.png\" class=\"vcex-image-img wpex-align-middle\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.museoarcheologiconapoli.it\/mann\/uploads\/2025\/07\/obvia.png 1500w, https:\/\/www.museoarcheologiconapoli.it\/mann\/uploads\/2025\/07\/obvia-300x200.png 300w, https:\/\/www.museoarcheologiconapoli.it\/mann\/uploads\/2025\/07\/obvia-1024x683.png 1024w, https:\/\/www.museoarcheologiconapoli.it\/mann\/uploads\/2025\/07\/obvia-768x512.png 768w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/><\/div><\/figure><div class=\"vcex-spacing wpex-w-100 wpex-clear\" style=\"height:20px;\"><\/div><style>.vcex-heading.vcex_6a04b846609d7{font-size:18px;font-weight:700;line-height:23px;}<\/style><div class=\"vcex-heading vcex-heading-plain vcex-module wpex-heading wpex-text-2xl vcex_6a04b846609d7\"><span class=\"vcex-heading-inner wpex-inline-block\">Progetto obvia<\/span><\/div><\/div><\/div><\/div><\/div><\/a><\/div><\/div><div class=\"wpex-post-cards-entry col col-2 span_1_of_2 post-5329 type-post cat-98 translation_priority-53\"><div class=\"wpex-card wpex-card-template_1368\"><a href=\"https:\/\/www.museoarcheologiconapoli.it\/en\/ecovalors\/\" aria-label=\"ECOValors\" class=\"wpex-card-inner wpex-no-underline wpex-inherit-color\"><div class=\"vc_row wpb_row vc_row-fluid wpex-relative wpex-vc_row-col-mb-0\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><figure class=\"vcex-image vcex-module vcex-fill-column\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><img width=\"1500\" height=\"1000\" src=\"https:\/\/www.museoarcheologiconapoli.it\/mann\/uploads\/2025\/07\/eco.png\" class=\"vcex-image-img wpex-align-middle\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.museoarcheologiconapoli.it\/mann\/uploads\/2025\/07\/eco.png 1500w, https:\/\/www.museoarcheologiconapoli.it\/mann\/uploads\/2025\/07\/eco-300x200.png 300w, https:\/\/www.museoarcheologiconapoli.it\/mann\/uploads\/2025\/07\/eco-1024x683.png 1024w, https:\/\/www.museoarcheologiconapoli.it\/mann\/uploads\/2025\/07\/eco-768x512.png 768w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/><\/div><\/figure><div class=\"vcex-spacing wpex-w-100 wpex-clear\" style=\"height:20px;\"><\/div><style>.vcex-heading.vcex_6a04b84668259{font-size:18px;font-weight:700;line-height:23px;}<\/style><div class=\"vcex-heading vcex-heading-plain vcex-module wpex-heading wpex-text-2xl vcex_6a04b84668259\"><span class=\"vcex-heading-inner wpex-inline-block\">ECOValors<\/span><\/div><\/div><\/div><\/div><\/div><\/a><\/div><\/div><\/div><\/div><\/div>[\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"Ecosustainaible project for Conservation and Valorization of color traces on Marble sculptures Questo progetto \u00e8 realizzato in collaborazione con il Dipartimento di Scienze e Tecnologie Chimiche dell\u2019Universit\u00e0 degli Studi di Roma \u201cTor Vergata\u201d, e segue i risultati del progetto di ricerca \u201cMANN in Colours\u201d. ECOValors partir\u00e0 infatti dall\u2019analisi dei risultati raggiunti da Cristiana Barandoni (ideatore&hellip;","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3071","page","type-page","status-publish","hentry","entry","no-media"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Projects - mann napoli|museo archeologico di napoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.museoarcheologiconapoli.it\/en\/projects\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Projects - mann napoli|museo archeologico di napoli\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.museoarcheologiconapoli.it\/en\/projects\/\" \/>\n<meta property=\"og:site_name\" content=\"mann napoli|museo archeologico di napoli\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MANNapoli\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-16T09:41:21+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@mannapoli\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.museoarcheologiconapoli.it\/en\/projects\/\",\"url\":\"https:\/\/www.museoarcheologiconapoli.it\/en\/projects\/\",\"name\":\"Projects - mann napoli|museo archeologico di napoli\",\"isPartOf\":{\"@id\":\"https:\/\/www.museoarcheologiconapoli.it\/#website\"},\"datePublished\":\"2025-07-01T13:57:05+00:00\",\"dateModified\":\"2025-07-16T09:41:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.museoarcheologiconapoli.it\/en\/projects\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.museoarcheologiconapoli.it\/en\/projects\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.museoarcheologiconapoli.it\/en\/projects\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.museoarcheologiconapoli.it\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projects\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.museoarcheologiconapoli.it\/#website\",\"url\":\"https:\/\/www.museoarcheologiconapoli.it\/\",\"name\":\"mann napoli|museo archeologico di napoli\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.museoarcheologiconapoli.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.museoarcheologiconapoli.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.museoarcheologiconapoli.it\/#organization\",\"name\":\"mann napoli|museo archeologico di napoli\",\"url\":\"https:\/\/www.museoarcheologiconapoli.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.museoarcheologiconapoli.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.museoarcheologiconapoli.it\/mann\/uploads\/2025\/06\/logo-title-black.svg\",\"contentUrl\":\"https:\/\/www.museoarcheologiconapoli.it\/mann\/uploads\/2025\/06\/logo-title-black.svg\",\"width\":1,\"height\":1,\"caption\":\"mann napoli|museo archeologico di napoli\"},\"image\":{\"@id\":\"https:\/\/www.museoarcheologiconapoli.it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/MANNapoli\",\"https:\/\/x.com\/mannapoli\",\"https:\/\/www.instagram.com\/museoarcheologiconapoli?igshid=yzwn4a82knl\",\"https:\/\/www.youtube.com\/@museoarcheologiconapoli\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Projects - mann napoli|museo archeologico di napoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.museoarcheologiconapoli.it\/en\/projects\/","og_locale":"en_US","og_type":"article","og_title":"Projects - mann napoli|museo archeologico di napoli","og_url":"https:\/\/www.museoarcheologiconapoli.it\/en\/projects\/","og_site_name":"mann napoli|museo archeologico di napoli","article_publisher":"https:\/\/www.facebook.com\/MANNapoli","article_modified_time":"2025-07-16T09:41:21+00:00","twitter_card":"summary_large_image","twitter_site":"@mannapoli","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.museoarcheologiconapoli.it\/en\/projects\/","url":"https:\/\/www.museoarcheologiconapoli.it\/en\/projects\/","name":"Projects - mann napoli|museo archeologico di napoli","isPartOf":{"@id":"https:\/\/www.museoarcheologiconapoli.it\/#website"},"datePublished":"2025-07-01T13:57:05+00:00","dateModified":"2025-07-16T09:41:21+00:00","breadcrumb":{"@id":"https:\/\/www.museoarcheologiconapoli.it\/en\/projects\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.museoarcheologiconapoli.it\/en\/projects\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.museoarcheologiconapoli.it\/en\/projects\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.museoarcheologiconapoli.it\/en\/"},{"@type":"ListItem","position":2,"name":"Projects"}]},{"@type":"WebSite","@id":"https:\/\/www.museoarcheologiconapoli.it\/#website","url":"https:\/\/www.museoarcheologiconapoli.it\/","name":"mann napoli|museo archeologico di napoli","description":"","publisher":{"@id":"https:\/\/www.museoarcheologiconapoli.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.museoarcheologiconapoli.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.museoarcheologiconapoli.it\/#organization","name":"mann napoli|museo archeologico di napoli","url":"https:\/\/www.museoarcheologiconapoli.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.museoarcheologiconapoli.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.museoarcheologiconapoli.it\/mann\/uploads\/2025\/06\/logo-title-black.svg","contentUrl":"https:\/\/www.museoarcheologiconapoli.it\/mann\/uploads\/2025\/06\/logo-title-black.svg","width":1,"height":1,"caption":"mann napoli|museo archeologico di napoli"},"image":{"@id":"https:\/\/www.museoarcheologiconapoli.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MANNapoli","https:\/\/x.com\/mannapoli","https:\/\/www.instagram.com\/museoarcheologiconapoli?igshid=yzwn4a82knl","https:\/\/www.youtube.com\/@museoarcheologiconapoli"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.museoarcheologiconapoli.it\/en\/wp-json\/wp\/v2\/pages\/3071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.museoarcheologiconapoli.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.museoarcheologiconapoli.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.museoarcheologiconapoli.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.museoarcheologiconapoli.it\/en\/wp-json\/wp\/v2\/comments?post=3071"}],"version-history":[{"count":1,"href":"https:\/\/www.museoarcheologiconapoli.it\/en\/wp-json\/wp\/v2\/pages\/3071\/revisions"}],"predecessor-version":[{"id":3072,"href":"https:\/\/www.museoarcheologiconapoli.it\/en\/wp-json\/wp\/v2\/pages\/3071\/revisions\/3072"}],"wp:attachment":[{"href":"https:\/\/www.museoarcheologiconapoli.it\/en\/wp-json\/wp\/v2\/media?parent=3071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}