{"id":38932,"date":"2025-11-28T15:12:08","date_gmt":"2025-11-28T15:12:08","guid":{"rendered":"https:\/\/www.museoarcheologiconapoli.it\/?post_type=just_event&#038;p=38932"},"modified":"2025-11-28T15:40:53","modified_gmt":"2025-11-28T15:40:53","slug":"international-day-of-persons-with-disabilities2025","status":"publish","type":"just_event","link":"https:\/\/www.museoarcheologiconapoli.it\/en\/event\/international-day-of-persons-with-disabilities2025\/","title":{"rendered":"International Day of Persons with Disabilities 2025"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_column_text css=&#8221;&#8221;]International Day of Persons with Disabilities 2025[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text css=&#8221;&#8221;]<strong>Il MANN per l\u2019accessibilit\u00e0 e la cultura inclusiva<\/strong><\/p>\n<p>In occasione del <strong>3 dicembre<\/strong>, il Museo Archeologico Nazionale di Napoli rinnova il suo impegno per rendere la cultura un bene condiviso e accessibile a tutti. Con un programma speciale di attivit\u00e0, il MANN invita bambini, famiglie e adulti a vivere esperienze inclusive che intrecciano conoscenza, creativit\u00e0 e partecipazione.[\/vc_column_text][vc_column_text css=&#8221;&#8221;]<strong><br \/>\nProgramma<\/strong><\/p>\n<p><strong>Mercoled\u00ec 3 dicembre<\/strong><br \/>\n<strong>ore 10.30<\/strong><br \/>\n<strong>Mitologia per tutti<\/strong>. Un laboratorio dedicato ai miti greco-romani, per scoprire insieme le storie degli d\u00e8i e cimentarsi nella riproduzione di un attributo divino. Un\u2019occasione per avvicinarsi al patrimonio antico con linguaggi multisensoriali e attivit\u00e0 pratiche.<\/p>\n<p>Attivit\u00e0 in italiano<br \/>\nDurata 90 min<br \/>\nAccessibilit\u00e0: per persone con disabilit\u00e0 visiva e cognitiva<br \/>\nCosto: gratuita per il disabile e un suo accompagnatore<\/p>\n<p><strong>Venerd\u00ec 5 dicembre<\/strong><br \/>\n<strong>ore 10.30<\/strong><br \/>\n<strong>Il Toro Farnese<\/strong>: toccare, ascoltare, scoprire. Una visita guidata alla celebre \u201cmontagna di marmo\u201d, straordinario capolavoro della scultura antica proveniente dalle Terme di Caracalla a Roma. I partecipanti saranno accompagnati alla scoperta dei dettagli e delle suggestioni di un mondo bucolico senza tempo, con percorsi progettati per favorire la fruizione e l\u2019accessibilit\u00e0 di tutti.<\/p>\n<p>Attivit\u00e0 in italiano<br \/>\nDurata 90 min<br \/>\nAccessibilit\u00e0: per persone con disabilit\u00e0 visiva e cognitiva<br \/>\nCosto: gratuita per il disabile e un suo accompagnatore[\/vc_column_text][vc_column_text css=&#8221;&#8221;]<strong>Venerd\u00ec 12 dicembre<\/strong><br \/>\n<strong>ore 10.30<\/strong><br \/>\n<strong>Le maschere e il teatro<\/strong>. Un tour multisensoriale per conoscere le principali caratteristiche del teatro antico, esplorare il ruolo delle maschere e soffermarsi sulle emozioni che esse evocano. Un percorso pensato per coinvolgere tutti i partecipanti, favorendo un\u2019esperienza inclusiva e accessibile che intreccia storia, individualit\u00e0 e creativit\u00e0.<\/p>\n<p>Attivit\u00e0 in italiano<br \/>\nDurata 90 min<br \/>\nAccessibilit\u00e0: per persone con disabilit\u00e0 visiva e cognitiva<br \/>\nCosto: gratuita per il disabile e un suo accompagnatore<\/p>\n<p>Prenotazione obbligatoria<br \/>\nServizi Educativi MANN: 0814422336[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"<p>3, 5 e 12 December 2025<\/p>\n","protected":false},"author":4,"featured_media":38936,"template":"","meta":{"_acf_changed":false,"_just_events_all_day":true,"_just_events_start_date":"2025-11-28 00:00:00","_just_events_end_date":"2025-12-12 23:59:00","_just_events_link":""},"event_category":[72],"class_list":["post-38932","just_event","type-just_event","status-publish","has-post-thumbnail","hentry","event_category-events","entry","has-media"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>International Day of Persons with Disabilities 2025 - mann napoli|museo archeologico di napoli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.museoarcheologiconapoli.it\/en\/event\/international-day-of-persons-with-disabilities2025\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"International Day of Persons with Disabilities 2025 - mann napoli|museo archeologico di napoli\" \/>\n<meta property=\"og:description\" content=\"3, 5 e 12 December 2025\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.museoarcheologiconapoli.it\/en\/event\/international-day-of-persons-with-disabilities2025\/\" \/>\n<meta property=\"og:site_name\" content=\"mann napoli|museo archeologico di napoli\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MANNapoli\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-28T15:40:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.museoarcheologiconapoli.it\/mann\/uploads\/2025\/11\/3dicembre25_Feed.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@mannapoli\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.museoarcheologiconapoli.it\/en\/event\/international-day-of-persons-with-disabilities2025\/\",\"url\":\"https:\/\/www.museoarcheologiconapoli.it\/en\/event\/international-day-of-persons-with-disabilities2025\/\",\"name\":\"International Day of Persons with Disabilities 2025 - mann napoli|museo archeologico di napoli\",\"isPartOf\":{\"@id\":\"https:\/\/www.museoarcheologiconapoli.it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.museoarcheologiconapoli.it\/en\/event\/international-day-of-persons-with-disabilities2025\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.museoarcheologiconapoli.it\/en\/event\/international-day-of-persons-with-disabilities2025\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.museoarcheologiconapoli.it\/mann\/uploads\/2025\/11\/3dicembre25_Feed.jpg\",\"datePublished\":\"2025-11-28T15:12:08+00:00\",\"dateModified\":\"2025-11-28T15:40:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.museoarcheologiconapoli.it\/en\/event\/international-day-of-persons-with-disabilities2025\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.museoarcheologiconapoli.it\/en\/event\/international-day-of-persons-with-disabilities2025\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.museoarcheologiconapoli.it\/en\/event\/international-day-of-persons-with-disabilities2025\/#primaryimage\",\"url\":\"https:\/\/www.museoarcheologiconapoli.it\/mann\/uploads\/2025\/11\/3dicembre25_Feed.jpg\",\"contentUrl\":\"https:\/\/www.museoarcheologiconapoli.it\/mann\/uploads\/2025\/11\/3dicembre25_Feed.jpg\",\"width\":1080,\"height\":1350,\"caption\":\"locandina giornata intenazionale delle persone con disabilit\u00e0\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.museoarcheologiconapoli.it\/en\/event\/international-day-of-persons-with-disabilities2025\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.museoarcheologiconapoli.it\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\/\/www.museoarcheologiconapoli.it\/events\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"International Day of Persons with Disabilities 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.museoarcheologiconapoli.it\/#website\",\"url\":\"https:\/\/www.museoarcheologiconapoli.it\/\",\"name\":\"mann napoli|museo archeologico di napoli\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.museoarcheologiconapoli.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.museoarcheologiconapoli.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.museoarcheologiconapoli.it\/#organization\",\"name\":\"mann napoli|museo archeologico di napoli\",\"url\":\"https:\/\/www.museoarcheologiconapoli.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.museoarcheologiconapoli.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.museoarcheologiconapoli.it\/mann\/uploads\/2025\/06\/logo-title-black.svg\",\"contentUrl\":\"https:\/\/www.museoarcheologiconapoli.it\/mann\/uploads\/2025\/06\/logo-title-black.svg\",\"width\":1,\"height\":1,\"caption\":\"mann napoli|museo archeologico di napoli\"},\"image\":{\"@id\":\"https:\/\/www.museoarcheologiconapoli.it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/MANNapoli\",\"https:\/\/x.com\/mannapoli\",\"https:\/\/www.instagram.com\/museoarcheologiconapoli?igshid=yzwn4a82knl\",\"https:\/\/www.youtube.com\/@museoarcheologiconapoli\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"International Day of Persons with Disabilities 2025 - mann napoli|museo archeologico di napoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.museoarcheologiconapoli.it\/en\/event\/international-day-of-persons-with-disabilities2025\/","og_locale":"en_US","og_type":"article","og_title":"International Day of Persons with Disabilities 2025 - mann napoli|museo archeologico di napoli","og_description":"3, 5 e 12 December 2025","og_url":"https:\/\/www.museoarcheologiconapoli.it\/en\/event\/international-day-of-persons-with-disabilities2025\/","og_site_name":"mann napoli|museo archeologico di napoli","article_publisher":"https:\/\/www.facebook.com\/MANNapoli","article_modified_time":"2025-11-28T15:40:53+00:00","og_image":[{"width":1080,"height":1350,"url":"https:\/\/www.museoarcheologiconapoli.it\/mann\/uploads\/2025\/11\/3dicembre25_Feed.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@mannapoli","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.museoarcheologiconapoli.it\/en\/event\/international-day-of-persons-with-disabilities2025\/","url":"https:\/\/www.museoarcheologiconapoli.it\/en\/event\/international-day-of-persons-with-disabilities2025\/","name":"International Day of Persons with Disabilities 2025 - mann napoli|museo archeologico di napoli","isPartOf":{"@id":"https:\/\/www.museoarcheologiconapoli.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.museoarcheologiconapoli.it\/en\/event\/international-day-of-persons-with-disabilities2025\/#primaryimage"},"image":{"@id":"https:\/\/www.museoarcheologiconapoli.it\/en\/event\/international-day-of-persons-with-disabilities2025\/#primaryimage"},"thumbnailUrl":"https:\/\/www.museoarcheologiconapoli.it\/mann\/uploads\/2025\/11\/3dicembre25_Feed.jpg","datePublished":"2025-11-28T15:12:08+00:00","dateModified":"2025-11-28T15:40:53+00:00","breadcrumb":{"@id":"https:\/\/www.museoarcheologiconapoli.it\/en\/event\/international-day-of-persons-with-disabilities2025\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.museoarcheologiconapoli.it\/en\/event\/international-day-of-persons-with-disabilities2025\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.museoarcheologiconapoli.it\/en\/event\/international-day-of-persons-with-disabilities2025\/#primaryimage","url":"https:\/\/www.museoarcheologiconapoli.it\/mann\/uploads\/2025\/11\/3dicembre25_Feed.jpg","contentUrl":"https:\/\/www.museoarcheologiconapoli.it\/mann\/uploads\/2025\/11\/3dicembre25_Feed.jpg","width":1080,"height":1350,"caption":"locandina giornata intenazionale delle persone con disabilit\u00e0"},{"@type":"BreadcrumbList","@id":"https:\/\/www.museoarcheologiconapoli.it\/en\/event\/international-day-of-persons-with-disabilities2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.museoarcheologiconapoli.it\/en\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/www.museoarcheologiconapoli.it\/events\/"},{"@type":"ListItem","position":3,"name":"International Day of Persons with Disabilities 2025"}]},{"@type":"WebSite","@id":"https:\/\/www.museoarcheologiconapoli.it\/#website","url":"https:\/\/www.museoarcheologiconapoli.it\/","name":"mann napoli|museo archeologico di napoli","description":"","publisher":{"@id":"https:\/\/www.museoarcheologiconapoli.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.museoarcheologiconapoli.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.museoarcheologiconapoli.it\/#organization","name":"mann napoli|museo archeologico di napoli","url":"https:\/\/www.museoarcheologiconapoli.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.museoarcheologiconapoli.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.museoarcheologiconapoli.it\/mann\/uploads\/2025\/06\/logo-title-black.svg","contentUrl":"https:\/\/www.museoarcheologiconapoli.it\/mann\/uploads\/2025\/06\/logo-title-black.svg","width":1,"height":1,"caption":"mann napoli|museo archeologico di napoli"},"image":{"@id":"https:\/\/www.museoarcheologiconapoli.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MANNapoli","https:\/\/x.com\/mannapoli","https:\/\/www.instagram.com\/museoarcheologiconapoli?igshid=yzwn4a82knl","https:\/\/www.youtube.com\/@museoarcheologiconapoli"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.museoarcheologiconapoli.it\/en\/wp-json\/wp\/v2\/just_event\/38932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.museoarcheologiconapoli.it\/en\/wp-json\/wp\/v2\/just_event"}],"about":[{"href":"https:\/\/www.museoarcheologiconapoli.it\/en\/wp-json\/wp\/v2\/types\/just_event"}],"author":[{"embeddable":true,"href":"https:\/\/www.museoarcheologiconapoli.it\/en\/wp-json\/wp\/v2\/users\/4"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.museoarcheologiconapoli.it\/en\/wp-json\/wp\/v2\/media\/38936"}],"wp:attachment":[{"href":"https:\/\/www.museoarcheologiconapoli.it\/en\/wp-json\/wp\/v2\/media?parent=38932"}],"wp:term":[{"taxonomy":"event_category","embeddable":true,"href":"https:\/\/www.museoarcheologiconapoli.it\/en\/wp-json\/wp\/v2\/event_category?post=38932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}